{"id":285,"date":"2026-02-10T08:42:10","date_gmt":"2022-07-18T15:30:38","guid":{"rendered":"https:\/\/moduline.it\/hold-manutentori-caldi-e-freddi\/"},"modified":"2026-02-16T16:08:52","modified_gmt":"2026-02-16T16:08:52","slug":"hold-mantenitori-caldi-e-freddi","status":"publish","type":"page","link":"https:\/\/moduline.it\/de\/hold-mantenitori-caldi-e-freddi\/","title":{"rendered":"[VECCHIA]Hold &#8211; Mantenitori Caldi e Freddi"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"285\" class=\"elementor elementor-285\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3550339 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3550339\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f29a6d\" data-id=\"9f29a6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4162c3 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b4162c3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">hold<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ab51c30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab51c30\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c9fc85a\" data-id=\"c9fc85a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5219ec6 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"5219ec6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"685\" height=\"1536\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/11\/Hold-Moduline--685x1536.png\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2048\" alt=\"Hold - Moduline\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/11\/Hold-Moduline--685x1536.png 685w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/11\/Hold-Moduline--134x300.png 134w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/11\/Hold-Moduline--457x1024.png 457w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/11\/Hold-Moduline--768x1722.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/11\/Hold-Moduline--913x2048.png 913w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/11\/Hold-Moduline-.png 714w\" sizes=\"(max-width: 685px) 100vw, 685px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-51af2d9 animated-slow elementor-invisible\" data-id=\"51af2d9\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9216b92 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9216b92\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Per un servizio di qualit\u00e0 <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbaedec elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"dbaedec\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Quando ci si siede a tavola, \u00e8 molto importante poter consumare le pietanze &#8211; sia calde che fredde &#8211; alla giusta temperatura. Ma, nelle ore di punta del servizio o in generale quando i clienti sono molto numerosi, non \u00e8 affatto semplice assicurare che la temperatura dei cibi sia sempre quella ottimale.<br \/><br \/>I mantenitori di temperatura HOLD di Moduline offrono la risposta definitiva a questo problema.<\/p><p><span style=\"background-color: var( --e-global-color-cc2b298 ); color: var( --e-global-color-ab43007 ); font-size: 1em;\">La gamma HOLD \u00e8 composta da due tipologie di prodotti: i mantenitori caldi Warm e i mantenitori freddi COLD.<\/span><\/p><p>I modelli WARM permettono di conservare le pietanze calde alla giusta temperatura senza disidratarle: sia attraverso il sistema di riscaldamento statico DELIWARM, sia quello ventilato abbinato al CLIMACHEF.<\/p><p>WARM permette di mantenere costante la temperatura di qualsiasi piatto &#8211; senza intaccarne n\u00e9 la qualit\u00e0 n\u00e9 l\u2019aspetto &#8211; per un tempo che varia, da pochi minuti, fino ad un massimo di 4 ore.<\/p><p>L\u2019offerta WARM si declina in 28 diverse versioni tutte dotate di controllo elettronico e prevede mantenitori d\u2019appoggio; con cassetti; da incasso; carrellati e da pavimento (quest\u2019ultimi a riscaldamento ventilato).<\/p><p>La gamma COLD \u00e8 rappresentata da 4 carrelli refrigerati, 2 positivi e 2 negativi. Questi ultimi permettono di servire piatti freddi come i desserts, la frutta e la verdura, alla temperatura ideale in ogni tipo di servizio, nel banqueting, nel servizio di mense e nella ristorazione commerciale.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7613ec8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7613ec8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa6c30a\" data-id=\"fa6c30a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-034c97a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"034c97a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\nWARM: il caldo statico con DELIWARM e quello ventilato con CLIMACHEF<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1c5bf7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c5bf7f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-128ba5e\" data-id=\"128ba5e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c70eab9 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c70eab9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il sistema di mantenimento caldo per conservare il gusto e la qualit\u00e0 degli elementi <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e74abdf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e74abdf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b14f27f\" data-id=\"b14f27f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f8965f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8965f7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2fe3420\" data-id=\"2fe3420\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9241f58 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"9241f58\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Con WARM nulla \u00e8 lasciato al caso quando si tratta di conciliare la tempestivit\u00e0 nel servizio con il perfetto mantenimento del gusto, della consistenza e dell\u2019aspetto tipici dei piatti appena cotti.<\/p><p>I mantenitori caldi statici Moduline sono a basso consumo energetico, garantiscono la massima efficienza nel servizio e l\u2019appetibilit\u00e0 assoluta di cibi. WARM si avvale, infatti, di una tecnologia avanzata che permette di non aggredire gli alimenti calibrando le temperature in maniera da salvaguardare sapori e fragranze.<\/p><p>Il sistema di riscaldamento, alimentato da una resistenza esterna alla camera e dotato di un preciso controllo elettronico della temperatura, \u00e8 in grado di conservare l\u2019umidit\u00e0 naturale negli alimenti, senza seccarli, molto pi\u00f9 a lungo dei normali mantenitori ventilati privi di controllo dell\u2019umidit\u00e0.<\/p><p>Grazie all\u2019esperienza maturata da Moduline nella progettazione dei forni statici Cook&amp;Hold, i mantenitori WARM di Moduline assicurano un risultato straordinario per ogni tipo di utilizzo: dalle mense al fast-food, dai ristoranti al banqueting e, pi\u00f9 in generale, in tutte le strutture pubbliche.<\/p><p>La gamma dei mantenitori statici DELIWARM \u00e8 composta da 25 modelli che variano a seconda delle diverse modalit\u00e0 di installazione e prevede modelli da banco, da incasso, con cassetti, e su ruote. Per le esigenze del servizio di grande taglia, Moduline ha previsto anche 6 modelli ventilati da pavimento, dotati del sistema CLIMACHEF (impiegato anche nei rigeneratori RETHERMA) che assicura il giusto grado di umidit\u00e0, evitando la disidratazione, la decolorazione e la perdita di sapore degli alimenti.<\/p><p>Questi modelli possono ospitare carrelli da 20 teglie GN 1\/1, 40 GN 1\/1 e &#8212; per le esigenze specifiche del banqueting &#8212; da 62 a 126 piatti per ciclo. In funzione di queste esigenze di carico \u00e8 previsto l\u2019impiego esclusivo del riscaldamento ventilato, dato che il sistema di riscaldamento statico non \u00e8 adatto ai servizi di grande taglia.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a08fb9e\" data-id=\"a08fb9e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0650fc uael-img-grid__column-1 hide-on-it uael-img-grid-mobile__column-1 uael-img-grid-tablet__column-3 uael-ins-normal elementor-widget elementor-widget-uael-image-gallery\" data-id=\"f0650fc\" data-element_type=\"widget\" data-settings=\"{&quot;gallery_columns&quot;:&quot;1&quot;,&quot;gallery_columns_mobile&quot;:&quot;1&quot;,&quot;gallery_columns_tablet&quot;:&quot;3&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;images_valign&quot;:&quot;flex-start&quot;}\" data-widget_type=\"uael-image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"uael-gallery-parent uael-caption- uael-gallery-unjustified\"><div class=\"uael-img-gallery-wrap uael-img-grid-wrap uael-img-grid-masonry-wrap\" data-filter-default=\"All\"><div class=\"uael-grid-item  uael-img-gallery-item-1\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/moduline.it\/en\/enhold\/hot-holding-equipment\/\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/03\/cop-1024x640.png\" class=\"attachment-large size-large wp-image-12033\" alt=\"Hold-warm Hot holding equipment\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/03\/cop-1024x640.png 1024w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/03\/cop-300x188.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/03\/cop-768x480.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/03\/cop-1536x960.png 1536w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/03\/cop-18x12.png 18w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/03\/cop.png 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cdfcdb uael-img-grid__column-1 hide-on-en uael-img-grid-mobile__column-1 uael-img-grid-tablet__column-3 uael-ins-normal elementor-widget elementor-widget-uael-image-gallery\" data-id=\"8cdfcdb\" data-element_type=\"widget\" data-settings=\"{&quot;gallery_columns&quot;:&quot;1&quot;,&quot;gallery_columns_mobile&quot;:&quot;1&quot;,&quot;gallery_columns_tablet&quot;:&quot;3&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;images_valign&quot;:&quot;flex-start&quot;}\" data-widget_type=\"uael-image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"uael-gallery-parent uael-caption- uael-gallery-unjustified\"><div class=\"uael-img-gallery-wrap uael-img-grid-wrap uael-img-grid-masonry-wrap\" data-filter-default=\"All\"><div class=\"uael-grid-item  uael-img-gallery-item-1\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/moduline.it\/de\/video-hold-mantenitori-caldi-e-freddi\/hold-warm\/\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/02\/cop-1024x640.jpg\" class=\"attachment-large size-large wp-image-11751\" alt=\"Hold-warm i manutentori caldi\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/02\/cop-1024x640.jpg 1024w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/02\/cop-300x188.jpg 300w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/02\/cop-768x480.jpg 768w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/02\/cop-1536x960.jpg 1536w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/02\/cop.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e597b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e597b4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e19dccb\" data-id=\"e19dccb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a9d5d80 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a9d5d80\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b30f895\" data-id=\"b30f895\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42aac0b animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"42aac0b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">GAMMA<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4152e0 animated-slow elementor-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-button\" data-id=\"f4152e0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:160,&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scarica il Catologo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d3adda0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3adda0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijk5MCIsInRvZ2dsZSI6ZmFsc2V9&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e024f2b elementor-invisible\" data-id=\"e024f2b\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-547be5c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"547be5c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">i mantenitori statici con <\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35b1282 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"35b1282\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><font color=\"#907e68\"><span style=\"font-size: 50px;\">deliwarm<\/span><\/font><\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5b77740 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b77740\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijk5MCIsInRvZ2dsZSI6ZmFsc2V9&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-539bdb4 elementor-invisible\" data-id=\"539bdb4\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ1OTUiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-23aa605 elementor-invisible\" data-id=\"23aa605\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0037b0e elementor-widget elementor-widget-image\" data-id=\"0037b0e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH031E-819x1024.png\" class=\"attachment-large size-large wp-image-4182\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH031E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH031E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH031E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH031E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH031E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH031E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6db91e elementor-widget elementor-widget-heading\" data-id=\"d6db91e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSH031E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7363894 elementor-widget elementor-widget-heading\" data-id=\"7363894\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">3 GN1\/1<br>Potenza elettrica 700W<br>Capacit\u00e0 prodotto 11kg<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ1OTgiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-e416308 elementor-invisible\" data-id=\"e416308\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d7bdf5 elementor-widget elementor-widget-image\" data-id=\"3d7bdf5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH051E-819x1024.png\" class=\"attachment-large size-large wp-image-4183\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH051E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH051E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH051E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH051E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH051E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH051E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be76b4c elementor-widget elementor-widget-heading\" data-id=\"be76b4c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSH051E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed8a2ad elementor-widget elementor-widget-heading\" data-id=\"ed8a2ad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5 GN1\/1<br>Potenza elettrica 1000W<br>Capacit\u00e0 prodotto 18kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MDEiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-726fb04 elementor-invisible\" data-id=\"726fb04\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9555b81 elementor-widget elementor-widget-image\" data-id=\"9555b81\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH052E-819x1024.png\" class=\"attachment-large size-large wp-image-4184\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH052E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH052E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH052E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH052E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH052E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSH052E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cbd9d9 elementor-widget elementor-widget-heading\" data-id=\"2cbd9d9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSH052E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffb31e8 elementor-widget elementor-widget-heading\" data-id=\"ffb31e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5 GN2\/1 - 10 GN1\/1<br>Potenza elettrica 1500W<br>Capacit\u00e0 prodotto 36kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MDEiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-ca32a03 elementor-invisible\" data-id=\"ca32a03\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9018320 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9018320\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e2033d\" data-id=\"8e2033d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8745ed3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8745ed3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MTMiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-5725fab elementor-invisible\" data-id=\"5725fab\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5434290 elementor-widget elementor-widget-image\" data-id=\"5434290\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001E-819x1024.png\" class=\"attachment-large size-large wp-image-4185\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b0f6b1 elementor-widget elementor-widget-heading\" data-id=\"8b0f6b1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSW001E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88a846a elementor-widget elementor-widget-heading\" data-id=\"88a846a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1 GN1\/1 h max 150<br>Potenza elettrica 700W<br>Capacit\u00e0 prodotto 6kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MTYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-827f250 elementor-invisible\" data-id=\"827f250\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc8659e elementor-widget elementor-widget-image\" data-id=\"fc8659e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002E-819x1024.png\" class=\"attachment-large size-large wp-image-4187\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-873815f elementor-widget elementor-widget-heading\" data-id=\"873815f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSW002E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44ade27 elementor-widget elementor-widget-heading\" data-id=\"44ade27\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2 GN1\/1 h max 150<br>Potenza elettrica 1000W<br>Capacit\u00e0 prodotto 12kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MjAiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-e79efa4 elementor-invisible\" data-id=\"e79efa4\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c20b0cc elementor-widget elementor-widget-image\" data-id=\"c20b0cc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW003E-819x1024.png\" class=\"attachment-large size-large wp-image-4189\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW003E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW003E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW003E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW003E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW003E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW003E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-764430a elementor-widget elementor-widget-heading\" data-id=\"764430a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSW003E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae36663 elementor-widget elementor-widget-heading\" data-id=\"ae36663\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2 GN1\/1 h max 150<br>Potenza elettrica 1000W<br>Capacit\u00e0 prodotto 18kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MzYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-9da8828 elementor-invisible\" data-id=\"9da8828\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a4880b elementor-widget elementor-widget-image\" data-id=\"6a4880b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001ER-819x1024.png\" class=\"attachment-large size-large wp-image-4186\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001ER-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001ER-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001ER-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001ER-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001ER-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW001ER.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b42cd88 elementor-widget elementor-widget-heading\" data-id=\"b42cd88\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSW001ER\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffc4fa4 elementor-widget elementor-widget-heading\" data-id=\"ffc4fa4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1 GN1\/1 h max 150<br>Potenza elettrica 700W<br>Capacit\u00e0 prodotto 6kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MzkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-93a077b elementor-invisible\" data-id=\"93a077b\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2a2719 elementor-widget elementor-widget-image\" data-id=\"a2a2719\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002ER-819x1024.png\" class=\"attachment-large size-large wp-image-4188\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002ER-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002ER-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002ER-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002ER-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002ER-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW002ER.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e7b0b5 elementor-widget elementor-widget-heading\" data-id=\"9e7b0b5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSW002ER\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1628385 elementor-widget elementor-widget-heading\" data-id=\"1628385\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2 GN1\/1 h max 150<br>Potenza elettrica 1000W<br>Capacit\u00e0 prodotto 12kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60a287b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60a287b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55a8e51\" data-id=\"55a8e51\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f39fe66 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f39fe66\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MDQiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-92eacc7 elementor-invisible\" data-id=\"92eacc7\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0e5792 elementor-widget elementor-widget-image\" data-id=\"f0e5792\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011E-819x1024.png\" class=\"attachment-large size-large wp-image-4190\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9de3bbf elementor-widget elementor-widget-heading\" data-id=\"9de3bbf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSW011E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb74c10 elementor-widget elementor-widget-heading\" data-id=\"eb74c10\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1 GN1\/1 h max 150<br>Potenza elettrica 700W<br>Capacit\u00e0 prodotto 6kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MDciLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-99c2f3d elementor-invisible\" data-id=\"99c2f3d\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebf7793 elementor-widget elementor-widget-image\" data-id=\"ebf7793\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012E-819x1024.png\" class=\"attachment-large size-large wp-image-4192\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6056f2 elementor-widget elementor-widget-heading\" data-id=\"e6056f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSW012E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3e625d elementor-widget elementor-widget-heading\" data-id=\"e3e625d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2 GN1\/1 h max 150<br>Potenza elettrica 1000W<br>Capacit\u00e0 prodotto 12kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MTAiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-15346a2 elementor-invisible\" data-id=\"15346a2\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab73cab elementor-widget elementor-widget-image\" data-id=\"ab73cab\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW013E-819x1024.png\" class=\"attachment-large size-large wp-image-4194\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW013E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW013E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW013E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW013E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW013E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW013E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bed0be0 elementor-widget elementor-widget-heading\" data-id=\"bed0be0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSW013E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8775872 elementor-widget elementor-widget-heading\" data-id=\"8775872\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3 GN1\/1 h max 150<br>Potenza elettrica 1000W<br>Capacit\u00e0 prodotto 18kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MjkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-2013183 elementor-invisible\" data-id=\"2013183\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8457004 elementor-widget elementor-widget-image\" data-id=\"8457004\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011ER-819x1024.png\" class=\"attachment-large size-large wp-image-4191\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011ER-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011ER-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011ER-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011ER-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011ER-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW011ER.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db6ec6f elementor-widget elementor-widget-heading\" data-id=\"db6ec6f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSW011ER\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb32352 elementor-widget elementor-widget-heading\" data-id=\"cb32352\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1 GN1\/1 h max 150<br>Potenza elettrica 700W<br>Capacit\u00e0 prodotto 6kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MzMiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-a0ef5f6 elementor-invisible\" data-id=\"a0ef5f6\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee682f0 elementor-widget elementor-widget-image\" data-id=\"ee682f0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012ER-819x1024.png\" class=\"attachment-large size-large wp-image-4193\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012ER-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012ER-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012ER-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012ER-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012ER-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW012ER.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6727c25 elementor-widget elementor-widget-heading\" data-id=\"6727c25\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSW012ER\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b404de elementor-widget elementor-widget-heading\" data-id=\"7b404de\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2 GN1\/1 h max 150<br>Potenza elettrica 1000W<br>Capacit\u00e0 prodotto 12kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28d75e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28d75e8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dfc3253\" data-id=\"dfc3253\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-97d9b19 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97d9b19\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d111c39 elementor-invisible\" data-id=\"d111c39\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MjMiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-69dbaf7 elementor-invisible\" data-id=\"69dbaf7\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f9b2e2 elementor-widget elementor-widget-image\" data-id=\"8f9b2e2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW212E-819x1024.png\" class=\"attachment-large size-large wp-image-4195\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW212E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW212E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW212E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW212E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW212E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW212E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7b6cc8 elementor-widget elementor-widget-heading\" data-id=\"a7b6cc8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSW212E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95503d7 elementor-widget elementor-widget-heading\" data-id=\"95503d7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2 GN1\/1 h max 150<br>Potenza elettrica 1400W<br>Capacit\u00e0 prodotto 12kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2MjYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-cdbcb1f elementor-invisible\" data-id=\"cdbcb1f\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5009541 elementor-widget elementor-widget-image\" data-id=\"5009541\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW313E-819x1024.png\" class=\"attachment-large size-large wp-image-4196\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW313E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW313E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW313E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW313E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW313E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HSW313E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9f2e44 elementor-widget elementor-widget-heading\" data-id=\"b9f2e44\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSW313E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fa1410 elementor-widget elementor-widget-heading\" data-id=\"6fa1410\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3 GN1\/1 h max 150<br>Potenza elettrica 2100W<br>Capacit\u00e0 prodotto 18kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d26fc4c elementor-invisible\" data-id=\"d26fc4c\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4cfcce6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4cfcce6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5628916\" data-id=\"5628916\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-14cdb14 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14cdb14\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2NDQiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-28b350e elementor-invisible\" data-id=\"28b350e\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d74a74 elementor-widget elementor-widget-image\" data-id=\"9d74a74\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT081E-819x1024.png\" class=\"attachment-large size-large wp-image-4176\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT081E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT081E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT081E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT081E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT081E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT081E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68ae10a elementor-widget elementor-widget-heading\" data-id=\"68ae10a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHT081E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-150ee4f elementor-widget elementor-widget-heading\" data-id=\"150ee4f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">8GN 1\/1<br>Potenza elettrica 1000W <br>Capacit\u00e0 prodotto 29kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2NDciLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-02ee751 elementor-invisible\" data-id=\"02ee751\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c990ca8 elementor-widget elementor-widget-image\" data-id=\"c990ca8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E-819x1024.png\" class=\"attachment-large size-large wp-image-4178\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73a29b7 elementor-widget elementor-widget-heading\" data-id=\"73a29b7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHT161E \n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f27ca76 elementor-widget elementor-widget-heading\" data-id=\"f27ca76\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">16GN 1\/1<br>Potenza elettrica 2000W<br>Capacit\u00e0 prodotto 58kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2NTAiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-68a4cda elementor-invisible\" data-id=\"68a4cda\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d5748b elementor-widget elementor-widget-image\" data-id=\"1d5748b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E-819x1024.png\" class=\"attachment-large size-large wp-image-4178\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT161E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea63a1d elementor-widget elementor-widget-heading\" data-id=\"ea63a1d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHT161EP\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a236a92 elementor-widget elementor-widget-heading\" data-id=\"a236a92\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">16GN 1\/1<br>Potenza elettrica 2000W<br>Capacit\u00e0 prodotto 58kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2NTciLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-c526061 elementor-invisible\" data-id=\"c526061\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b586b69 elementor-widget elementor-widget-image\" data-id=\"b586b69\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT281E-819x1024.png\" class=\"attachment-large size-large wp-image-4180\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT281E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT281E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT281E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT281E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT281E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT281E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca5e5e2 elementor-widget elementor-widget-heading\" data-id=\"ca5e5e2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHT281E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31d9351 elementor-widget elementor-widget-heading\" data-id=\"31d9351\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">8+8GN 1\/1<br>Potenza elettrica 2000W<br>Capacit\u00e0 prodotto 58kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2NjIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-e5854ad elementor-invisible\" data-id=\"e5854ad\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85e448d elementor-widget elementor-widget-image\" data-id=\"85e448d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT052E-819x1024.png\" class=\"attachment-large size-large wp-image-4175\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT052E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT052E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT052E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT052E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT052E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT052E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d836496 elementor-widget elementor-widget-heading\" data-id=\"d836496\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHT052E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60fee35 elementor-widget elementor-widget-heading\" data-id=\"60fee35\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5 GN2\/1 - 10 GN1\/1<br>Potenza elettrica 1500W <br>Capacit\u00e0 prodotto 36kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78fcb50 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"78fcb50\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-218dd93\" data-id=\"218dd93\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5868f60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5868f60\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2NjkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-49ca4e1 elementor-invisible\" data-id=\"49ca4e1\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c84bda3 elementor-widget elementor-widget-image\" data-id=\"c84bda3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT082E-819x1024.png\" class=\"attachment-large size-large wp-image-4177\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT082E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT082E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT082E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT082E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT082E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT082E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76675e1 elementor-widget elementor-widget-heading\" data-id=\"76675e1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHT082E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d30a35f elementor-widget elementor-widget-heading\" data-id=\"d30a35f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">8 GN2\/1 - 16 GN1\/1\nPotenza elettrica 1500W <br>Capacit\u00e0 prodotto 58kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2NzYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-83e20bd elementor-invisible\" data-id=\"83e20bd\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20c7273 elementor-widget elementor-widget-image\" data-id=\"20c7273\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E-819x1024.png\" class=\"attachment-large size-large wp-image-4179\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3aa10c2 elementor-widget elementor-widget-heading\" data-id=\"3aa10c2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHT162E <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4ed359 elementor-widget elementor-widget-heading\" data-id=\"e4ed359\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">16 GN2\/1 - 32GN1\/1<br>Potenza elettrica 3000W <br>Capacit\u00e0 prodotto 115kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2ODAiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-7128158 elementor-invisible\" data-id=\"7128158\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96710d8 elementor-widget elementor-widget-image\" data-id=\"96710d8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E-819x1024.png\" class=\"attachment-large size-large wp-image-4179\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT162E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cfff39 elementor-widget elementor-widget-heading\" data-id=\"4cfff39\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHT162EP\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0f0f35 elementor-widget elementor-widget-heading\" data-id=\"c0f0f35\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">16 GN2\/1 - 32 GN1\/1<br>Potenza elettrica 3000W <br>Capacit\u00e0 prodotto 115kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2OTEiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-6118b42 elementor-invisible\" data-id=\"6118b42\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd92975 elementor-widget elementor-widget-image\" data-id=\"fd92975\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E-819x1024.png\" class=\"attachment-large size-large wp-image-4181\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa80dd0 elementor-widget elementor-widget-heading\" data-id=\"aa80dd0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHT282E \n <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2903ba elementor-widget elementor-widget-heading\" data-id=\"a2903ba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">8+8 GN2\/1 - 16+16GN1\/1<br>Potenza elettrica 3000W <br>Capacit\u00e0 prodotto 115kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2OTYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-c1df364 elementor-invisible\" data-id=\"c1df364\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-951b258 elementor-widget elementor-widget-image\" data-id=\"951b258\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E-819x1024.png\" class=\"attachment-large size-large wp-image-4181\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHT282E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e42943d elementor-widget elementor-widget-heading\" data-id=\"e42943d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHT282EP\n <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6eaf13 elementor-widget elementor-widget-heading\" data-id=\"b6eaf13\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">8+8 GN2\/1 - 16+16GN1\/1<br>Potenza elettrica 3000W <br>Capacit\u00e0 prodotto 115kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a89813a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a89813a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c70f274\" data-id=\"c70f274\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-69fecb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69fecb7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-129c36a\" data-id=\"129c36a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3ba039 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b3ba039\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">i mantenitori ventilati con <\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e98a73 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3e98a73\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><font color=\"#907e68\"><span style=\"font-size: 50px;\">climachef<\/span><\/font><\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a749faa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a749faa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-e249c7b elementor-invisible\" data-id=\"e249c7b\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b13ce3 elementor-widget elementor-widget-image\" data-id=\"5b13ce3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF20E-819x1024.png\" class=\"attachment-large size-large wp-image-4169\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF20E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF20E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF20E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF20E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF20E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF20E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3cf189 elementor-widget elementor-widget-heading\" data-id=\"f3cf189\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHFF20E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-368b833 elementor-widget elementor-widget-heading\" data-id=\"368b833\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">20 GN1\/1<br>Potenza elettrica 6300W<br>Capacit\u00e0 prodotto 72kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ3MDIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-8b3ac49 elementor-invisible\" data-id=\"8b3ac49\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35a1eb1 elementor-widget elementor-widget-image\" data-id=\"35a1eb1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF22E-819x1024.png\" class=\"attachment-large size-large wp-image-4170\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF22E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF22E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF22E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF22E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF22E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF22E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0064717 elementor-widget elementor-widget-heading\" data-id=\"0064717\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHFF22E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78af9e9 elementor-widget elementor-widget-heading\" data-id=\"78af9e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">20 GN1\/1<br>Potenza elettrica 6300W<br>Capacit\u00e0 prodotto 72kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ3MDUiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-af7c760 elementor-invisible\" data-id=\"af7c760\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfb6ebf elementor-widget elementor-widget-image\" data-id=\"dfb6ebf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT20E-819x1024.png\" class=\"attachment-large size-large wp-image-4173\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT20E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT20E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT20E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT20E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT20E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT20E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cacbfd elementor-widget elementor-widget-heading\" data-id=\"9cacbfd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHFT20E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ff09eb elementor-widget elementor-widget-heading\" data-id=\"1ff09eb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">20 GN1\/1<br>Potenza elettrica 6300W<br>Capacit\u00e0 prodotto 72kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ3MDgiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-b7ee306 elementor-invisible\" data-id=\"b7ee306\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b933be elementor-widget elementor-widget-image\" data-id=\"5b933be\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT22E-819x1024.png\" class=\"attachment-large size-large wp-image-4174\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT22E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT22E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT22E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT22E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT22E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFT22E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ff722e elementor-widget elementor-widget-heading\" data-id=\"9ff722e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHFT22E\n\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f313846 elementor-widget elementor-widget-heading\" data-id=\"f313846\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">20 GN1\/1<br>Potenza elettrica 6300W<br>Capacit\u00e0 prodotto 72kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ3MTEiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-1000d8d elementor-invisible\" data-id=\"1000d8d\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5afffa6 elementor-widget elementor-widget-image\" data-id=\"5afffa6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF40E-819x1024.png\" class=\"attachment-large size-large wp-image-4171\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF40E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF40E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF40E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF40E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF40E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF40E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b404ca elementor-widget elementor-widget-heading\" data-id=\"1b404ca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHFF40E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddee9b3 elementor-widget elementor-widget-heading\" data-id=\"ddee9b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">40 GN1\/1 - 20 GN2\/1<br>Potenza elettrica 7800W<br>Capacit\u00e0 prodotto 144kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ3MTQiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-5bf95f3 elementor-invisible\" data-id=\"5bf95f3\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fbdcdd elementor-widget elementor-widget-image\" data-id=\"6fbdcdd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF42E-819x1024.png\" class=\"attachment-large size-large wp-image-4172\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF42E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF42E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF42E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF42E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF42E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HHFF42E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0dc9e47 elementor-widget elementor-widget-heading\" data-id=\"0dc9e47\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHFF42E\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7845a43 elementor-widget elementor-widget-heading\" data-id=\"7845a43\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">40 GN1\/1 - 20 GN2\/1<br>Potenza elettrica 7800W<br>Capacit\u00e0 prodotto 144kg<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10bb7c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10bb7c4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e3af4e\" data-id=\"2e3af4e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c77c02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c77c02\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f11715e\" data-id=\"f11715e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e2e7de elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2e2e7de\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">i mantenitori freddi ventilati<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7b354b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b354b4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ3MjAiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0e481d2 elementor-invisible\" data-id=\"0e481d2\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8bef767 elementor-widget elementor-widget-image\" data-id=\"8bef767\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT122E-819x1024.png\" class=\"attachment-large size-large wp-image-4165\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT122E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT122E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT122E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT122E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT122E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT122E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc1574b elementor-widget elementor-widget-heading\" data-id=\"dc1574b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">HCT122E<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f5fb05 elementor-widget elementor-widget-heading\" data-id=\"7f5fb05\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"elementor-heading-title elementor-size-default\">12 GN2\/1 - 24 GN1\/1<br>\nPotenza elettrica 550W<br>\nCapacit\u00e0 piatti 64\u00f8\n 200-260 - 32\u00f8\n 270-320<\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ3MjYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-bb4d316 elementor-invisible\" data-id=\"bb4d316\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d8763c elementor-widget elementor-widget-image\" data-id=\"2d8763c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT122E-819x1024.png\" class=\"attachment-large size-large wp-image-4167\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT122E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT122E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT122E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT122E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT122E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT122E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfe4c25 elementor-widget elementor-widget-heading\" data-id=\"bfe4c25\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">HFT122E<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cacd33 elementor-widget elementor-widget-heading\" data-id=\"4cacd33\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">12 GN2\/1 - 24 GN1\/1<br>\nPotenza elettrica 550W<br>\nCapacit\u00e0 piatti 48\u00f8 200-260 - 24\u00f8 270-320<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ3MTciLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b71c4fd elementor-invisible\" data-id=\"b71c4fd\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-068038e elementor-widget elementor-widget-image\" data-id=\"068038e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT162E-819x1024.png\" class=\"attachment-large size-large wp-image-4166\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT162E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT162E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT162E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT162E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT162E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HCT162E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-217a232 elementor-widget elementor-widget-heading\" data-id=\"217a232\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">HCT162E<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e8af69 elementor-widget elementor-widget-heading\" data-id=\"6e8af69\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"elementor-heading-title elementor-size-default\">16 GN2\/1 - 32 GN1\/1<br>Potenza elettrica 200W<br>\nCapacit\u00e0 piatti 64\u00f8 200-260 - 32\u00f8 270-320<\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ3MjMiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2d194ac elementor-invisible\" data-id=\"2d194ac\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e9f579 elementor-widget elementor-widget-image\" data-id=\"8e9f579\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT162E-819x1024.png\" class=\"attachment-large size-large wp-image-4168\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT162E-819x1024.png 819w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT162E-240x300.png 240w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT162E-768x960.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT162E-1229x1536.png 1229w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT162E-1638x2048.png 1638w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/HFT162E.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21acfb0 elementor-widget elementor-widget-heading\" data-id=\"21acfb0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">HFT162E<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b98d1a2 elementor-widget elementor-widget-heading\" data-id=\"b98d1a2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"elementor-heading-title elementor-size-default\">16 GN2\/1 - 32 GN1\/1<br>Potenza elettrica 200W<br>Capacit\u00e0 piatti 48\u00f8\n 200-260 - 24\u00f8\n 270-320<\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c5499f1 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c5499f1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23b8c27\" data-id=\"23b8c27\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aad1dc9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"aad1dc9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7ac3afe\" data-id=\"7ac3afe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0369b3a animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"0369b3a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Servire in tavola le vostre ricette nei momenti critici<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a11eea elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2a11eea\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">COME SE FOSSERO STATE APPENA COTTE <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-82323f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82323f5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1771342\" data-id=\"1771342\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11f632a elementor-invisible elementor-widget elementor-widget-image\" data-id=\"11f632a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/hold-1-1024x1024.png\" class=\"attachment-large size-large wp-image-5503\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/hold-1-1024x1024.png 1024w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/hold-1-300x300.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/hold-1-150x150.png 150w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/hold-1-768x768.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/hold-1-1536x1536.png 1536w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/hold-1-2048x2048.png 2048w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/hold-1.png 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-016c650\" data-id=\"016c650\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3f3c2b animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e3f3c2b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><b style=\"background-color: transparent; color: var( --e-global-color-ab43007 );\">HSH-HSW<\/b><span style=\"background-color: transparent; color: var( --e-global-color-ab43007 );\">&nbsp;<\/span><\/p>\n<ul>\n<li>Il sistema di riscaldamento DeliWarm estende notevolmente i tempi di mantenimento a fine cottura senza disidratare le pietanze, in alcuni casi fino a 4 ore.&nbsp;<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fc954f animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"9fc954f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>Il controllo elettronico \u00e8 estremamente intuitivo e facilmente utilizzabile anche da un personale meno esperto.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f670751 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"f670751\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li><span style=\"background-color: transparent; color: var( --e-global-color-ab43007 );\">Lo sfiato manuale frontale permette la regolazione della naturale umidit\u00e0 dei cibi da mantenere. &#8211;\u00a0La maniglia dei cassetti HSW \u00e8 ergonomica, completamente incassata e la chiusura \u00e8 magnetica.<\/span><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f049c73 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"f049c73\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li><span style=\"background-color: transparent; color: var( --e-global-color-ab43007 );\">I piedini a ventosa permettono una facile installazione da banco.<\/span><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aabc875 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"aabc875\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li><span style=\"background-color: transparent; color: var( --e-global-color-ab43007 );\">La assenza di ventilazione forzata previene l&#8217;essicamento del prodotto e permette di risparmiare acqua, evitando l\u2019aggiunta di umidit\u00e0 nella camera di riscaldamento.<\/span><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd6fd70 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"dd6fd70\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li><span style=\"background-color: transparent; color: var( --e-global-color-ab43007 );\">Le guide telescopiche dei cassetti HSW, in acciaio inox, sono di robusta costruzione e resistenti all\u2019uso intensivo.<\/span><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecd47f3 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"ecd47f3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li><span style=\"background-color: transparent; color: var( --e-global-color-ab43007 );\">L\u2019isolamento della camera di riscaldamento, ottenuto con l\u2019uso di materiali altamente coibentati, garantisce una minore dispersione di calore.<\/span><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1279e64 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1279e64\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li><span style=\"background-color: transparent; color: var( --e-global-color-ab43007 );\">La guarnizione dei modelli HSH \u00e8 composta di silicone resistente alle alte temperature ed \u00e8 facilmente intercambiabile.<\/span><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e49d103 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e49d103\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li><span style=\"background-color: transparent; color: var( --e-global-color-ab43007 );\">Nei modelli da appoggio o da banco le paratie porta teglie sono facilmente smontabili e lavabili in lavastoviglie.<\/span><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e99819 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3e99819\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li><span style=\"background-color: transparent; color: var( --e-global-color-ab43007 );\">La camera a tenuta stagna, ad angoli arrotondati, rende le operazioni di pulizia facili e sicure.<\/span><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9788e7e animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"9788e7e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><b>HHT<\/b>\u00a0<\/p><ul><li>Il controllo elettronico \u00e8 estremamente intuitivo e facilmente utilizzabile anche da un personale meno esperto.\u00a0<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f9fcef animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"5f9fcef\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>Lo sfiato manuale sulla porta permette la perfetta regolazione della naturale umidit\u00e0 dei cibi da mantenere.\u00a0<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3759da1 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3759da1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>La maniglia della porta \u00e8 ergonomica, completamente incassata e la chiusura \u00e8 magnetica.\u00a0<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c8bcb8 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6c8bcb8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>La dotazione dei modelli HHT include di serie: paracolpi perimetrali in plastica; quattro ruote del diametro di 125 mm (di cui due rotanti e con freno); maniglie laterali per la spinta e la guida, che garantiscono una perfetta mobilit\u00e0.\u00a0<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a56a44 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3a56a44\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>La guarnizione della porta \u00e8 composta di silicone resistente alle alte temperature ed \u00e8 facilmente intercambiabile.\u00a0<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc1223b animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"dc1223b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>L&#8217;assenza di ventilazione forzata previene l&#8217;essicamento del prodotto e permette di risparmiare acqua evitando l\u2019aggiunta di umidit\u00e0 nella camera di riscaldamento.\u00a0<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acab6d8 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"acab6d8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>Le paratie porta teglie sono facilmente smontabili e lavabili.\u00a0<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ceb7b7 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3ceb7b7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul>\n<li>La camera a tenuta stagna e gli angoli arrotondati rendono le operazioni di pulizia facili e sicure&nbsp;<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7b5bb8 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"d7b5bb8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><b style=\"background-color: transparent; color: var( --e-global-color-ab43007 );\">HSH-HSW<\/b><span style=\"background-color: transparent; color: var( --e-global-color-ab43007 );\">\u00a0<\/span><\/p><ul><li>Il sistema di riscaldamento DeliWarm estende notevolmente i tempi di mantenimento a fine cottura senza disidratare le pietanze, in alcuni casi fino a 4 ore.\u00a0<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e78a2d8 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e78a2d8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>Il controllo elettronico \u00e8 estremamente intuitivo e facilmente utilizzabile anche da un personale meno esperto.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b4b7cd animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6b4b7cd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>Lo sfiato manuale frontale permette la regolazione della naturale umidit\u00e0 dei cibi da mantenere.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57a76e7 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"57a76e7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li><span style=\"background-color: transparent; color: var( --e-global-color-ab43007 );\">La maniglia dei cassetti HSW \u00e8 ergonomica, completamente incassata e la chiusura \u00e8 magnetica.\u00a0<\/span><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7b0dfe animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"d7b0dfe\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>I piedini a ventosa permettono una facile installazione da banco.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc853c1 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"dc853c1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>La assenza di ventilazione forzata previene l&#8217;essicamento del prodotto e permette di risparmiare acqua, evitando l\u2019aggiunta di umidit\u00e0 nella camera di riscaldamento.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ade6d53 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"ade6d53\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>Le guide telescopiche dei cassetti HSW, in acciaio inox, sono di robusta costruzione e resistenti all\u2019uso intensivo.\u00a0<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-057499e animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"057499e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>L\u2019isolamento della camera di riscaldamento, ottenuto con l\u2019uso di materiali altamente coibentati, garantisce una minore dispersione di calore.\u00a0<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c0d0aa animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"4c0d0aa\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>La guarnizione dei modelli HSH \u00e8 composta di silicone resistente alle alte temperature ed \u00e8 facilmente intercambiabile.\u00a0<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b4d9ff animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1b4d9ff\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>Nei modelli da appoggio o da banco le paratie porta teglie sono facilmente smontabili e lavabili in lavastoviglie.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b17d03c animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b17d03c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul>\n<li>La camera a tenuta stagna, ad angoli arrotondati, rende le operazioni di pulizia facili e sicure.<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f10c86 elementor-hidden-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4f10c86\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71c861d\" data-id=\"71c861d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b617c1a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b617c1a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pannello Comandi<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09dfb15 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"09dfb15\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHFF-HHFT<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6e6b74c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e6b74c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-52f8684\" data-id=\"52f8684\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b8f2fe animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"4b8f2fe\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1397\" height=\"2048\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-11-e1669982509880-1397x2048.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-3960\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-11-e1669982509880-1397x2048.png 1397w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-11-e1669982509880-205x300.png 205w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-11-e1669982509880-698x1024.png 698w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-11-e1669982509880-768x1126.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-11-e1669982509880-1048x1536.png 1048w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-11-e1669982509880.png 1091w\" sizes=\"(max-width: 1397px) 100vw, 1397px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c661cdb elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c661cdb\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9f99b8\" data-id=\"e9f99b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f66e03f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f66e03f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pannello Comandi<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd2afc animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7fd2afc\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HHFF-HHFT<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f20dccf animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"f20dccf\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"912\" height=\"2048\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/hold-1--912x2048.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-7784\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/hold-1--912x2048.png 912w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/hold-1--134x300.png 134w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/hold-1--456x1024.png 456w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/hold-1--768x1724.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/hold-1--684x1536.png 684w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/hold-1-.png 713w\" sizes=\"(max-width: 912px) 100vw, 912px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc05a93 elementor-widget elementor-widget-text-editor\" data-id=\"fc05a93\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>1. Tasto ON\/OFF <\/strong><\/p><p><strong>2. Display LCD touch-screen 4.3\u2033 <\/strong><\/p><p><strong>3. Manopola encoder per navigare tra le funzioni del forno e impostare tutti i parametri di rigenerazione <\/strong><\/p><p><strong>4. Tasto START\/STOP <\/strong><\/p><p><strong>5. Tasto luce camera<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4815bde elementor-hidden-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4815bde\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52a8be0\" data-id=\"52a8be0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f370869 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f370869\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pannello Comandi\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc2fdba animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cc2fdba\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSH-HSW-HHT<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3daf92c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3daf92c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0045e91\" data-id=\"0045e91\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-471ee4f animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"471ee4f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"944\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-9-e1669982580504-2048x944.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-3961\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-9-e1669982580504-2048x944.png 2048w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-9-e1669982580504-300x138.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-9-e1669982580504-1024x472.png 1024w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-9-e1669982580504-768x354.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-9-e1669982580504-1536x708.png 1536w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-9-e1669982580504.png 1600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a4228b elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a4228b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-82f879f\" data-id=\"82f879f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-993e880 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"993e880\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pannello Comandi\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d771dd9 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d771dd9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HSH-HSW-HHT<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c185fa animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"9c185fa\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"743\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/hold-2.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-7785\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/hold-2.png 1600w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/hold-2-300x139.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/hold-2-1024x475.png 1024w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/hold-2-768x356.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/hold-2-1536x713.png 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db246d3 elementor-widget elementor-widget-text-editor\" data-id=\"db246d3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>1. Display digitale <\/strong><\/p><p><strong>2. Tasto ON\/OFF <\/strong><\/p><p><strong>3. Tasti incremento\/decremento temperatura e tempo <\/strong><\/p><p><strong>4. Tasto START\/STOP <\/strong><\/p><p><strong>5. Inserimento del blocco tastiera PadLock tenendo premuti, contemporaneamente tasto ON\/OFF e START\/STOP<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e9bb4bf elementor-hidden-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e9bb4bf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7efbf9\" data-id=\"e7efbf9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e038d5a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e038d5a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pannello Comandi\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fbe1a1 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3fbe1a1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HCT-HFT<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eb12d3f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb12d3f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ad1d2d4\" data-id=\"ad1d2d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2909a5 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"f2909a5\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1810\" height=\"2048\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold--1810x2048.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-8619\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold--1810x2048.png 1810w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold--265x300.png 265w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold--905x1024.png 905w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold--768x869.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold--1358x1536.png 1358w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold-.png 1414w\" sizes=\"(max-width: 1810px) 100vw, 1810px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26c327f elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26c327f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20e8ae9\" data-id=\"20e8ae9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a36b25 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4a36b25\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pannello Comandi\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57d46ab animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"57d46ab\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HCT-HFT<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c86a8a animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"4c86a8a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1844\" height=\"2048\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold-1844x2048.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-8620\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold-1844x2048.png 1844w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold-270x300.png 270w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold-922x1024.png 922w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold-768x853.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold-1383x1536.png 1383w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/Pannello-comandi-Hold.png 1440w\" sizes=\"(max-width: 1844px) 100vw, 1844px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1959d3 elementor-widget elementor-widget-text-editor\" data-id=\"f1959d3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>1. Pannello di regolazione e visualizzazione digitale della temperatura <\/strong><\/p><p><strong>2. Interruttore principale ON\/OFF<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cf4248 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7cf4248\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1a59fd\" data-id=\"e1a59fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7a192b8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7a192b8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cc3dcf3\" data-id=\"cc3dcf3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26d5572 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"26d5572\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CARATTERISTICHE<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf8d74 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4bf8d74\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Modalit\u00e0 di funzionamento<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58db709 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58db709\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9056483\" data-id=\"9056483\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f7ce1e elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-image\" data-id=\"3f7ce1e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1018\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-805x1024.png\" class=\"attachment-large size-large wp-image-3886\" alt=\"Hold caratteristiche\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-805x1024.png 805w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-236x300.png 236w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-768x977.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01.png 859w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a48d36 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-image\" data-id=\"1a48d36\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1018\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-805x1024.png\" class=\"attachment-large size-large wp-image-3887\" alt=\"Hold caratteristiche 2\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-805x1024.png 805w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-236x300.png 236w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-768x977.png 768w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02.png 859w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2f7dec1\" data-id=\"2f7dec1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5b192e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"5b192e0\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-69713c3\" data-id=\"69713c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7936c09 elementor-widget elementor-widget-image\" data-id=\"7936c09\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"583\" height=\"583\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-min-7.png\" class=\"attachment-large size-large wp-image-5892\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-min-7.png 583w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-min-7-300x300.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/01-min-7-150x150.png 150w\" sizes=\"(max-width: 583px) 100vw, 583px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c8d1b1b\" data-id=\"c8d1b1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c89768f elementor-widget elementor-widget-text-editor\" data-id=\"c89768f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Temperature regolabili da +30\u00b0C a +120\u00b0C (sui modelli HSH-HSW-HHT).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6dda24d elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"6dda24d\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-684f439\" data-id=\"684f439\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84bc490 elementor-widget elementor-widget-image\" data-id=\"84bc490\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"583\" height=\"583\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-min-7.png\" class=\"attachment-large size-large wp-image-5893\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-min-7.png 583w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-min-7-300x300.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/02-min-7-150x150.png 150w\" sizes=\"(max-width: 583px) 100vw, 583px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cab2b44\" data-id=\"cab2b44\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a80f62 elementor-widget elementor-widget-text-editor\" data-id=\"5a80f62\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Temperature regolabili da +30\u00b0C a +90\u00b0C (sui modelli HHFF-HHFT).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-efc2aaf elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"efc2aaf\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-de820cd\" data-id=\"de820cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-570c7ac elementor-widget elementor-widget-image\" data-id=\"570c7ac\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"583\" height=\"583\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/03-min-6.png\" class=\"attachment-large size-large wp-image-5894\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/03-min-6.png 583w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/03-min-6-300x300.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/03-min-6-150x150.png 150w\" sizes=\"(max-width: 583px) 100vw, 583px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0d9e410\" data-id=\"0d9e410\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ebfcaa elementor-widget elementor-widget-text-editor\" data-id=\"0ebfcaa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Le bassissime potenze installate e il perfetto controllo della temperatura garantiscono consumi minimi di energia elettrica (sui modelli HSH, HSW, HHT)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-21acd04 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"21acd04\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-20c78a1\" data-id=\"20c78a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4644f6 elementor-widget elementor-widget-image\" data-id=\"b4644f6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"583\" height=\"583\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/04-min-5.png\" class=\"attachment-large size-large wp-image-5895\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/04-min-5.png 583w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/04-min-5-300x300.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/04-min-5-150x150.png 150w\" sizes=\"(max-width: 583px) 100vw, 583px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b49a964\" data-id=\"b49a964\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be3f997 elementor-widget elementor-widget-text-editor\" data-id=\"be3f997\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Il controllo digitale rende possibile la regolazione dei parametri di tempo; temperatura; umidit\u00e0; temperatura al cuore e la regolazione dei cicli per piatti o per teglie (sui modelli HHFF- HHFT).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0411301 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"0411301\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7e39358\" data-id=\"7e39358\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66ea023 elementor-widget elementor-widget-image\" data-id=\"66ea023\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"583\" height=\"583\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/05-min-5.png\" class=\"attachment-large size-large wp-image-5896\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/05-min-5.png 583w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/05-min-5-300x300.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/05-min-5-150x150.png 150w\" sizes=\"(max-width: 583px) 100vw, 583px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-46eab0b\" data-id=\"46eab0b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f0e605 elementor-widget elementor-widget-text-editor\" data-id=\"0f0e605\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Il sistema di blocco tastiera con password Pad Lock garantisce allo chef la massima protezione dei dati o l\u2019involontaria interruzione del programma di cottura (sui modelli HHFF- HHFT).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e4f1b55 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"e4f1b55\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-45afa55\" data-id=\"45afa55\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db101ef elementor-widget elementor-widget-image\" data-id=\"db101ef\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"583\" height=\"583\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/06-min-5.png\" class=\"attachment-large size-large wp-image-5897\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/06-min-5.png 583w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/06-min-5-300x300.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/06-min-5-150x150.png 150w\" sizes=\"(max-width: 583px) 100vw, 583px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d83e1c8\" data-id=\"d83e1c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35b8006 elementor-widget elementor-widget-text-editor\" data-id=\"35b8006\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Il sistema ProTime permette di impostare la data e l\u2019ora nelle quali l\u2019utente desidera che il forno si preriscaldi o inizi un programma di rigenerazione (sui modelli HHFF, HHFT).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ce28ca4 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"ce28ca4\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6d6cf92\" data-id=\"6d6cf92\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b35a79 elementor-widget elementor-widget-image\" data-id=\"6b35a79\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"583\" height=\"583\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/07-min-5.png\" class=\"attachment-large size-large wp-image-5898\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/07-min-5.png 583w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/07-min-5-300x300.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2022\/12\/07-min-5-150x150.png 150w\" sizes=\"(max-width: 583px) 100vw, 583px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0a46401\" data-id=\"0a46401\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5e18b0 elementor-widget elementor-widget-text-editor\" data-id=\"e5e18b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>La sonda al cuore controlla il raggiungimento della temperatura al cuore desiderata. Si possono registrare fino a 30 diverse temperature al cuore alla fine del processo e salvarle nel report HACCP (sui modelli HHFF- HHFT).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40b28aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40b28aa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4dbb9b4\" data-id=\"4dbb9b4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8296bd1 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"8296bd1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-838ae29\" data-id=\"838ae29\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23e2404 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"23e2404\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">EXTRAS<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8d34cfb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d34cfb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-263b62e elementor-invisible\" data-id=\"263b62e\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfb6ca9 elementor-widget elementor-widget-image\" data-id=\"cfb6ca9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"233\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/01-5.png\" class=\"attachment-large size-large wp-image-6434\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/01-5.png 921w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/01-5-300x87.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/01-5-768x223.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afa5196 elementor-widget elementor-widget-heading\" data-id=\"afa5196\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Carrelli<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7027cd elementor-widget elementor-widget-text-editor\" data-id=\"f7027cd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Per teglie GN e per piatti (sui modelli HHFF- HHFT).<\/p><div id=\"_tcx-fe6ix8syzd\" class=\"_tc_offscreeneded\">\u00a0<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a796c79 elementor-invisible\" data-id=\"a796c79\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-747c1f0 elementor-widget elementor-widget-image\" data-id=\"747c1f0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"233\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/02-5.png\" class=\"attachment-large size-large wp-image-6435\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/02-5.png 921w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/02-5-300x87.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/02-5-768x223.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e36ad06 elementor-widget elementor-widget-heading\" data-id=\"e36ad06\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Coperture termiche    <\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edbc78f elementor-widget elementor-widget-text-editor\" data-id=\"edbc78f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Per carrelli GN e per piatti (sui modelli HHFF- HHFT).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d6f2ce4 elementor-invisible\" data-id=\"d6f2ce4\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe6b2b1 elementor-widget elementor-widget-image\" data-id=\"fe6b2b1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"233\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/03-5.png\" class=\"attachment-large size-large wp-image-6436\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/03-5.png 921w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/03-5-300x87.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/03-5-768x223.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fbb668 elementor-widget elementor-widget-heading\" data-id=\"6fbb668\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Riduzione della velocit\u00e0 dei moto-ventilatori e della potenza del riscaldamento<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f819a4d elementor-widget elementor-widget-text-editor\" data-id=\"f819a4d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>La riduzione della velocit\u00e0 di rotazione dei moto-ventilatori SpeedGrade abbinata alla riduzione della potenza del riscaldamento (opzionale sui modelli HHFF- HHFT).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-37e7f97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37e7f97\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3480388 elementor-invisible\" data-id=\"3480388\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d89994 elementor-widget elementor-widget-image\" data-id=\"8d89994\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"233\" src=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/04-5.png\" class=\"attachment-large size-large wp-image-6437\" alt=\"\" srcset=\"https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/04-5.png 921w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/04-5-300x87.png 300w, https:\/\/moduline.it\/wp-content\/uploads\/2023\/01\/04-5-768x223.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9355565 elementor-widget elementor-widget-heading\" data-id=\"9355565\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Lampeggiante luminoso<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5481e09 elementor-widget elementor-widget-text-editor\" data-id=\"5481e09\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Per le versioni passanti, indica la fine del ciclo di mantenimento sul lato opposto all&#8217;entrata del mantenitore (opzionale sui modelli HHFF -HHFT<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-174cb80 elementor-invisible\" data-id=\"174cb80\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1a350bc elementor-invisible\" data-id=\"1a350bc\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>hold Per un servizio di qualit\u00e0 Quando ci si siede a tavola, \u00e8 molto importante poter consumare le pietanze &#8211; sia calde che fredde &#8211; alla giusta temperatura. Ma, nelle ore di punta del servizio o in generale quando i clienti sono molto numerosi, non \u00e8 affatto semplice assicurare che la temperatura dei cibi sia [&hellip;]<\/p>","protected":false},"author":308,"featured_media":0,"parent":0,"menu_order":13,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-285","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[VECCHIA]Hold - Mantenitori Caldi e Freddi - Moduline.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/moduline.it\/de\/hold-mantenitori-caldi-e-freddi\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[VECCHIA]Hold - Mantenitori Caldi e Freddi - Moduline.it\" \/>\n<meta property=\"og:description\" content=\"hold Per un servizio di qualit\u00e0 Quando ci si siede a tavola, \u00e8 molto importante poter consumare le pietanze &#8211; sia calde che fredde &#8211; all\" \/>\n<meta property=\"og:url\" content=\"https:\/\/moduline.it\/de\/hold-mantenitori-caldi-e-freddi\/\" \/>\n<meta property=\"og:site_name\" content=\"Moduline.it\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/modulinesrl\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-16T16:08:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/moduline.it\/wp-content\/uploads\/2022\/11\/Hold-Moduline--685x1536.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"22\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/moduline.it\\\/hold-mantenitori-caldi-e-freddi\\\/\",\"url\":\"https:\\\/\\\/moduline.it\\\/hold-mantenitori-caldi-e-freddi\\\/\",\"name\":\"[VECCHIA]Hold - Mantenitori Caldi e Freddi - Moduline.it\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moduline.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/moduline.it\\\/hold-mantenitori-caldi-e-freddi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/moduline.it\\\/hold-mantenitori-caldi-e-freddi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/moduline.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Hold-Moduline--685x1536.png\",\"datePublished\":\"2022-07-18T15:30:38+00:00\",\"dateModified\":\"2026-02-16T16:08:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/moduline.it\\\/hold-mantenitori-caldi-e-freddi\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/moduline.it\\\/hold-mantenitori-caldi-e-freddi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/moduline.it\\\/hold-mantenitori-caldi-e-freddi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/moduline.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Hold-Moduline--685x1536.png\",\"contentUrl\":\"https:\\\/\\\/moduline.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Hold-Moduline--685x1536.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/moduline.it\\\/hold-mantenitori-caldi-e-freddi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/moduline.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[VECCHIA]Hold &#8211; Mantenitori Caldi e Freddi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/moduline.it\\\/#website\",\"url\":\"https:\\\/\\\/moduline.it\\\/\",\"name\":\"Moduline.it\",\"description\":\"Macchinari per cucine professionali e per catering istituzionali.\",\"publisher\":{\"@id\":\"https:\\\/\\\/moduline.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/moduline.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/moduline.it\\\/#organization\",\"name\":\"Moduline s.r.l.\",\"url\":\"https:\\\/\\\/moduline.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/moduline.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/moduline.it\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Risorsa-21000px.png\",\"contentUrl\":\"https:\\\/\\\/moduline.it\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Risorsa-21000px.png\",\"width\":1000,\"height\":543,\"caption\":\"Moduline s.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/moduline.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/modulinesrl\",\"https:\\\/\\\/www.instagram.com\\\/modulinesrl\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/modulinesrl\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[VECCHIA]Hold - Mantenitori Caldi e Freddi - Moduline.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/moduline.it\/de\/hold-mantenitori-caldi-e-freddi\/","og_locale":"de_DE","og_type":"article","og_title":"[VECCHIA]Hold - Mantenitori Caldi e Freddi - Moduline.it","og_description":"hold Per un servizio di qualit\u00e0 Quando ci si siede a tavola, \u00e8 molto importante poter consumare le pietanze &#8211; sia calde che fredde &#8211; all","og_url":"https:\/\/moduline.it\/de\/hold-mantenitori-caldi-e-freddi\/","og_site_name":"Moduline.it","article_publisher":"https:\/\/www.facebook.com\/modulinesrl","article_modified_time":"2026-02-16T16:08:52+00:00","og_image":[{"url":"https:\/\/moduline.it\/wp-content\/uploads\/2022\/11\/Hold-Moduline--685x1536.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"22\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/moduline.it\/hold-mantenitori-caldi-e-freddi\/","url":"https:\/\/moduline.it\/hold-mantenitori-caldi-e-freddi\/","name":"[VECCHIA]Hold - Mantenitori Caldi e Freddi - Moduline.it","isPartOf":{"@id":"https:\/\/moduline.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/moduline.it\/hold-mantenitori-caldi-e-freddi\/#primaryimage"},"image":{"@id":"https:\/\/moduline.it\/hold-mantenitori-caldi-e-freddi\/#primaryimage"},"thumbnailUrl":"https:\/\/moduline.it\/wp-content\/uploads\/2022\/11\/Hold-Moduline--685x1536.png","datePublished":"2022-07-18T15:30:38+00:00","dateModified":"2026-02-16T16:08:52+00:00","breadcrumb":{"@id":"https:\/\/moduline.it\/hold-mantenitori-caldi-e-freddi\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/moduline.it\/hold-mantenitori-caldi-e-freddi\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/moduline.it\/hold-mantenitori-caldi-e-freddi\/#primaryimage","url":"https:\/\/moduline.it\/wp-content\/uploads\/2022\/11\/Hold-Moduline--685x1536.png","contentUrl":"https:\/\/moduline.it\/wp-content\/uploads\/2022\/11\/Hold-Moduline--685x1536.png"},{"@type":"BreadcrumbList","@id":"https:\/\/moduline.it\/hold-mantenitori-caldi-e-freddi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/moduline.it\/"},{"@type":"ListItem","position":2,"name":"[VECCHIA]Hold &#8211; Mantenitori Caldi e Freddi"}]},{"@type":"WebSite","@id":"https:\/\/moduline.it\/#website","url":"https:\/\/moduline.it\/","name":"Moduline.it","description":"Macchinari per cucine professionali e per catering istituzionali.","publisher":{"@id":"https:\/\/moduline.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/moduline.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/moduline.it\/#organization","name":"Moduline s.r.l.","url":"https:\/\/moduline.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/moduline.it\/#\/schema\/logo\/image\/","url":"https:\/\/moduline.it\/wp-content\/uploads\/2022\/07\/Risorsa-21000px.png","contentUrl":"https:\/\/moduline.it\/wp-content\/uploads\/2022\/07\/Risorsa-21000px.png","width":1000,"height":543,"caption":"Moduline s.r.l."},"image":{"@id":"https:\/\/moduline.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/modulinesrl","https:\/\/www.instagram.com\/modulinesrl\/","https:\/\/www.linkedin.com\/company\/modulinesrl\/"]}]}},"_links":{"self":[{"href":"https:\/\/moduline.it\/de\/wp-json\/wp\/v2\/pages\/285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moduline.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/moduline.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/moduline.it\/de\/wp-json\/wp\/v2\/users\/308"}],"replies":[{"embeddable":true,"href":"https:\/\/moduline.it\/de\/wp-json\/wp\/v2\/comments?post=285"}],"version-history":[{"count":8,"href":"https:\/\/moduline.it\/de\/wp-json\/wp\/v2\/pages\/285\/revisions"}],"predecessor-version":[{"id":18695,"href":"https:\/\/moduline.it\/de\/wp-json\/wp\/v2\/pages\/285\/revisions\/18695"}],"wp:attachment":[{"href":"https:\/\/moduline.it\/de\/wp-json\/wp\/v2\/media?parent=285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}